{"id":696,"date":"2023-02-10T09:36:11","date_gmt":"2023-02-10T16:36:11","guid":{"rendered":"https:\/\/suzukiassociation.org\/?p=696"},"modified":"2023-02-10T09:36:14","modified_gmt":"2023-02-10T16:36:14","slug":"the-wonder-of-the-possible-suzuki-in-canada","status":"publish","type":"post","link":"https:\/\/suzukiassociation.org\/pt\/2023\/02\/10\/the-wonder-of-the-possible-suzuki-in-canada\/","title":{"rendered":"A maravilha do poss\u00edvel: Suzuki no Canad\u00e1"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Os anos de 2020-2021 foram um per\u00edodo de desafios sem precedentes para muitos na comunidade Suzuki canadense. Muitos professores continuam a sentir os efeitos da redu\u00e7\u00e3o do n\u00famero de matr\u00edculas de alunos, da perda de oportunidades de apresenta\u00e7\u00e3o e da sinergia din\u00e2mica que \u00e9 criada quando tocamos m\u00fasica ao vivo junto com nossos alunos Suzuki e nossos colegas. Em algumas partes do pa\u00eds, aspectos da apresenta\u00e7\u00e3o est\u00e3o retornando, dando a todos n\u00f3s um pouco de luz para caminhar!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas esse per\u00edodo tamb\u00e9m nos proporcionou muitas ocasi\u00f5es para refletir sobre o que significa sermos administradores da mensagem universal do Dr. Suzuki: criar um ambiente em que todas as crian\u00e7as tenham uma educa\u00e7\u00e3o musical de qualidade, que ser\u00e1 transformadora para o mundo. Ao nos lembrarmos dessa mensagem, sentimos gratid\u00e3o pelos colegas, fam\u00edlias e crian\u00e7as que, direta ou indiretamente, nos ensinaram muitas li\u00e7\u00f5es sobre o poder da arte de confortar, unir e oferecer esperan\u00e7a ao mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tamb\u00e9m foi um ano em que o slogan do underground brit\u00e2nico \"Mind the Gap\" ganhou mais significado: como podemos preencher coletivamente a lacuna entre aqueles que podem e aqueles que n\u00e3o podem ter acesso a aulas de m\u00fasica Suzuki de qualidade? Como n\u00f3s, professores, podemos nos manter flex\u00edveis e abertos no meio da lacuna entre diversos pontos de vista, ao mesmo tempo em que mantemos nossa capacidade de ouvir e nossa compaix\u00e3o consciente em alta?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como somos afortunados neste momento por termos a m\u00fasica e as crian\u00e7as como far\u00f3is que nos impulsionam a encontrar maneiras de criar um mundo diferente e mais emp\u00e1tico que reconhe\u00e7a e deixe espa\u00e7o para nossas diferen\u00e7as e permita que todas as vozes do coral tenham seu lugar para cantar ao sol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A aproxima\u00e7\u00e3o de um novo ano \u00e9 um momento importante para sonhar, para reservar um tempo para pensar sobre o que pode ser poss\u00edvel na Suzuki Canad\u00e1. Talvez um futuro que tenha professores da Suzuki para cada instrumento em cada prov\u00edncia e territ\u00f3rio. Ou um futuro em que o financiamento p\u00fablico apoiaria as escolas Suzuki, criando ambientes de aprendizado para professores e alunos. Talvez um futuro em que os instrutores canadenses possam viajar para \u00e1reas remotas e de dif\u00edcil acesso para desenvolver uma forte comunidade Suzuki local. Nosso futuro poderia incluir uma forte associa\u00e7\u00e3o de ex-alunos e suas fam\u00edlias que desejam apoiar suas experi\u00eancias Suzuki que mudaram suas vidas para as gera\u00e7\u00f5es futuras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tamb\u00e9m \u00e9 o momento de estender nossa gratid\u00e3o e agradecimento aos in\u00fameros l\u00edderes, professores e instrutores Suzuki que visitaram nosso pa\u00eds nos \u00faltimos quarenta anos ou mais. Sua lideran\u00e7a inicial, seu carisma e seu compromisso com os professores e alunos canadenses da Suzuki plantaram as sementes de onde estamos hoje.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os anos de 2020-2021 foram um per\u00edodo de desafios sem precedentes para muitos na comunidade Suzuki canadense. Muitos professores continuam a sentir os efeitos da redu\u00e7\u00e3o do n\u00famero de matr\u00edculas de alunos, da perda de oportunidades de apresenta\u00e7\u00e3o e da sinergia din\u00e2mica que \u00e9 criada quando tocamos m\u00fasica ao vivo com nossos alunos Suzuki e nossos colegas. Em alguns...<\/p>","protected":false},"author":3,"featured_media":323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"pmpro_default_level":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[66],"tags":[],"class_list":["post-696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada","pmpro-has-access"],"acf":[],"taxonomy_info":{"category":[{"value":66,"label":"Canada"}]},"featured_image_src_large":["https:\/\/suzukiassociation.org\/wp-content\/uploads\/2023\/01\/saa-logo.png",640,640,false],"author_info":{"display_name":"Moonlit Media","author_link":"https:\/\/suzukiassociation.org\/pt\/author\/moonlit\/"},"comment_info":6,"category_info":[{"term_id":66,"name":"Canada","slug":"canada","term_group":0,"term_taxonomy_id":66,"taxonomy":"category","description":"","parent":0,"count":10,"filter":"raw","cat_ID":66,"category_count":10,"category_description":"","cat_name":"Canada","category_nicename":"canada","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/posts\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":0,"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/posts\/696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/media\/323"}],"wp:attachment":[{"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/media?parent=696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/categories?post=696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suzukiassociation.org\/pt\/wp-json\/wp\/v2\/tags?post=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}