{"id":82323,"date":"2025-11-18T10:29:08","date_gmt":"2025-11-18T17:29:08","guid":{"rendered":"https:\/\/suzukiassociation.org\/?post_type=tribe_events&#038;p=82323"},"modified":"2025-11-20T11:12:27","modified_gmt":"2025-11-20T18:12:27","slug":"new-england-suzuki-institute-2","status":"publish","type":"tribe_events","link":"https:\/\/suzukiassociation.org\/fr\/event\/new-england-suzuki-institute-2\/","title":{"rendered":"Institut Suzuki de Nouvelle-Angleterre"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La NESI s'installe sur le campus pittoresque du Colby College pour une semaine de musique et d'apprentissage. NESI s'engage \u00e0 offrir un programme complet et de qualit\u00e9 pour tous les \u00e2ges dans une atmosph\u00e8re d'attention individuelle. Nous proposons<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/pretwinkle.html\"> <span style=\"font-weight: 400;\">Pr\u00e9-p\u00e9tale<\/span><\/a><span style=\"font-weight: 400;\">,<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/budding_artist.html\"> <span style=\"font-weight: 400;\">Artiste en herbe<\/span><\/a><span style=\"font-weight: 400;\">,<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/young_artist.html\"> <span style=\"font-weight: 400;\">Jeune artiste<\/span><\/a><span style=\"font-weight: 400;\"> et<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/rising_artist.html\"> <span style=\"font-weight: 400;\">Artiste en devenir<\/span><\/a><span style=\"font-weight: 400;\"> programmes pour violon, alto, violoncelle, piano et guitare. Tous les \u00e9tudiants ont la possibilit\u00e9 de se produire lors d'un r\u00e9cital en solo.<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/recitals.html\"> <span style=\"font-weight: 400;\">Activit\u00e9s en soir\u00e9e<\/span><\/a><span style=\"font-weight: 400;\"> Parmi les activit\u00e9s propos\u00e9es, citons un feu de camp \u00e0 l'\u00e9chelle de l'institut, une conf\u00e9rence pour les parents avec nos cliniciens experts pendant que les \u00e9l\u00e8ves regardent un film \u00e0 c\u00f4t\u00e9, le tr\u00e8s populaire r\u00e9cital de la facult\u00e9, une contre-danse avec notre propre orchestre de violons, et des r\u00e9citals de musique de chambre, d'orchestre et de groupe pour terminer la semaine.  Des activit\u00e9s sp\u00e9ciales pour les adolescents sont organis\u00e9es chaque soir.  Des loisirs pour tous sont propos\u00e9s au centre sportif du coll\u00e8ge, qui comprend une piscine. Veuillez consulter notre site web pour plus de d\u00e9tails !<\/span><a href=\"http:\/\/www.newenglandsuzukiinstitute.org\"> <span style=\"font-weight: 400;\">\u00a0http:\/\/www.newenglandsuzukiinstitute.org<\/span><\/a><\/p>\n<p><b>Frais de scolarit\u00e9 :<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Inscription : $125 (appliqu\u00e9 aux frais)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pr\u00e9-trinquette : $298<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Artiste en herbe (violon, alto, violoncelle - livre 1-2 ; piano, guitare - livres 1-3) : $561<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Young Artist (violon, alto, violoncelle - livres 3-5 ; piano, guitare - livre 4-5) : $670<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Artiste en devenir (violon, alto, violoncelle - livres 6+ ; piano, guitare - livres 5-6+) : $793<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Possibilit\u00e9s d'enrichissement suppl\u00e9mentaires et cours optionnels pour les fr\u00e8res et s\u0153urs \u2013 $130\/classe<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ensemble parental \u2013 $150<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voir notre<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/fees.html\"> <span style=\"font-weight: 400;\">Page des taxes de l'Institut<\/span><\/a><span style=\"font-weight: 400;\"> pour une r\u00e9partition plus d\u00e9taill\u00e9e des niveaux et des frais de cours de ma\u00eetre pour les instruments secondaires.<\/span><a href=\"https:\/\/www.newenglandsuzukiinstitute.org\/fees.html\"><span style=\"font-weight: 400;\">\u00a0<\/span><\/a><\/p>\n<p><b>Logement et repas<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Les tarifs s'entendent par personne pour six nuits, du dimanche au vendredi, et tous les repas sont servis sous forme de buffet \u00e0 volont\u00e9, du d\u00eener du dimanche au petit d\u00e9jeuner du samedi. Ce tarif inclut le linge de maison. Un adulte, qui est soit le parent de l'\u00e9tudiant, soit un tuteur d\u00e9sign\u00e9 par les parents, doit accompagner chaque \u00e9tudiant dans le dortoir. Cet adulte doit r\u00e9server une chambre en plus de celle de son enfant.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">4 ans et moins - gratuit<\/span><\/p>\n<p><span style=\"font-weight: 400;\">5 ans - Adultes - Chambre et pension sur le campus : $495<\/span><\/p>\n<p><b>Loisirs :<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Le centre sportif du Colby College dispose d'une piscine et d'une salle de fitness.  Un magnifique mus\u00e9e d'art permet de se d\u00e9tendre.  Le campus dispose \u00e9galement de nombreux espaces verts qui sont parfaits pour des parties spontan\u00e9es de tag, de football ou de frisbee !  Il y a de belles pistes pour faire du v\u00e9lo ou de la trottinette, ainsi qu'un vaste r\u00e9seau de sentiers pour marcher ou courir dans l'arboretum du campus.  L'\u00e9tablissement propose \u00e9galement une navette gratuite vers le centre-ville de Waterville, qui abrite de nombreux restaurants exceptionnels et des boutiques uniques.<\/span><\/p>\n<p><b>Autres informations :<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Colby, situ\u00e9 dans le centre du Maine, est facilement accessible en voiture, en avion ou en bus.  Il existe des liaisons a\u00e9riennes depuis l'a\u00e9roport international de Portland (75 minutes de son) ou l'a\u00e9roport international de Bangor (60 minutes au nord).  Il existe \u00e9galement des liaisons par bus depuis New York, Boston, Portland et Bangor.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Le NESI s'installe sur le campus pittoresque du Colby College pour une semaine consacr\u00e9e \u00e0 la musique et \u00e0 l'apprentissage. Le NESI s'engage \u00e0 proposer un programme complet et de qualit\u00e9 pour tous les \u00e2ges dans\u2026<\/p>","protected":false},"author":220838,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"pmpro_default_level":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[736],"class_list":["post-82323","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-institute","pmpro-has-access","cat_institute"],"acf":[],"taxonomy_info":{"tribe_events_cat":[{"value":736,"label":"Institute"}]},"featured_image_src_large":false,"author_info":{"display_name":"Yasmin Craig Vitalius","author_link":"https:\/\/suzukiassociation.org\/fr\/author\/yasminvitalius-com\/"},"comment_info":"","ticketed":false,"_links":{"self":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tribe_events\/82323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/users\/220838"}],"version-history":[{"count":2,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tribe_events\/82323\/revisions"}],"predecessor-version":[{"id":82929,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tribe_events\/82323\/revisions\/82929"}],"wp:attachment":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/media?parent=82323"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tags?post=82323"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=82323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}