{"id":696,"date":"2023-02-10T09:36:11","date_gmt":"2023-02-10T16:36:11","guid":{"rendered":"https:\/\/suzukiassociation.org\/?p=696"},"modified":"2023-02-10T09:36:14","modified_gmt":"2023-02-10T16:36:14","slug":"the-wonder-of-the-possible-suzuki-in-canada","status":"publish","type":"post","link":"https:\/\/suzukiassociation.org\/fr\/2023\/02\/10\/the-wonder-of-the-possible-suzuki-in-canada\/","title":{"rendered":"L'\u00e9merveillement du possible : Suzuki au Canada"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les ann\u00e9es 2020-2021 ont \u00e9t\u00e9 une p\u00e9riode de d\u00e9fis sans pr\u00e9c\u00e9dent pour de nombreux membres de la communaut\u00e9 Suzuki canadienne. De nombreux enseignants continuent de ressentir les effets de la baisse du nombre d'\u00e9l\u00e8ves, de la perte d'occasions de se produire et de la synergie dynamique qui se cr\u00e9e lorsque nous jouons de la musique en direct avec nos \u00e9l\u00e8ves Suzuki et nos coll\u00e8gues. Dans certaines r\u00e9gions du pays, certains aspects de l'interpr\u00e9tation reviennent, ce qui nous donne \u00e0 tous un peu de lumi\u00e8re pour marcher !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais cette p\u00e9riode nous a \u00e9galement donn\u00e9 de nombreuses occasions de r\u00e9fl\u00e9chir \u00e0 ce que signifie \u00eatre les gardiens du message universel du Dr Suzuki : cr\u00e9er un environnement o\u00f9 chaque enfant b\u00e9n\u00e9ficie d'une \u00e9ducation musicale de qualit\u00e9, ce qui aura un effet transformateur sur le monde. En nous rappelant ce message, nous \u00e9prouvons de la gratitude pour ces coll\u00e8gues, ces familles et ces enfants qui, directement ou indirectement, nous ont enseign\u00e9 de nombreuses le\u00e7ons sur le pouvoir de l'art de r\u00e9conforter, de nous rassembler et d'offrir de l'espoir \u00e0 notre monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette ann\u00e9e a \u00e9galement \u00e9t\u00e9 une ann\u00e9e o\u00f9 le slogan underground britannique \"Mind the Gap\" a pris plus de sens : comment combler collectivement le foss\u00e9 entre ceux qui peuvent et ceux qui ne peuvent pas acc\u00e9der \u00e0 des cours de musique Suzuki de qualit\u00e9 ? Comment pouvons-nous, en tant qu'enseignants, rester flexibles et ouverts au milieu du foss\u00e9 entre les diff\u00e9rents points de vue, tout en gardant nos casquettes d'\u00e9coute et notre compassion attentive \u00e0 un niveau \u00e9lev\u00e9 ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle chance nous avons aujourd'hui d'avoir la musique et les enfants comme balises pour nous propulser vers l'avant et trouver des moyens de cr\u00e9er un monde diff\u00e9rent, plus empathique, qui reconnaisse et laisse de l'espace \u00e0 nos diff\u00e9rences et permette \u00e0 toutes les voix de la chorale de chanter au soleil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'approche d'une nouvelle ann\u00e9e est un moment important pour r\u00eaver, pour prendre le temps de s'interroger sur ce qui pourrait \u00eatre possible \u00e0 Suzuki Canada. Peut-\u00eatre un avenir o\u00f9 il y aurait des professeurs Suzuki pour chaque instrument dans chaque province et territoire. Ou un avenir o\u00f9 le financement public soutiendrait les \u00e9coles Suzuki en cr\u00e9ant des environnements d'apprentissage pour les enseignants et les \u00e9l\u00e8ves. Peut-\u00eatre un avenir o\u00f9 les formateurs canadiens peuvent se rendre dans des r\u00e9gions \u00e9loign\u00e9es et inaccessibles pour d\u00e9velopper une communaut\u00e9 Suzuki locale forte. Notre avenir pourrait inclure une solide association d'anciens \u00e9l\u00e8ves et de leurs familles qui souhaitent transmettre aux g\u00e9n\u00e9rations futures les exp\u00e9riences Suzuki qui ont chang\u00e9 leur vie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C'est aussi le moment d'exprimer notre gratitude et nos remerciements aux innombrables leaders, professeurs de Suzuki et formateurs qui ont visit\u00e9 notre pays au cours des quarante derni\u00e8res ann\u00e9es. Leur leadership, leur charisme et leur engagement envers les enseignants et les \u00e9l\u00e8ves canadiens de Suzuki ont jet\u00e9 les bases de ce que nous sommes aujourd'hui.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les ann\u00e9es 2020-2021 ont \u00e9t\u00e9 une p\u00e9riode de d\u00e9fis sans pr\u00e9c\u00e9dent pour de nombreux membres de la communaut\u00e9 Suzuki canadienne. De nombreux enseignants continuent de ressentir les effets de la baisse du nombre d'\u00e9l\u00e8ves, de la perte d'occasions de se produire et de la synergie dynamique qui se cr\u00e9e lorsque nous jouons de la musique en direct avec nos \u00e9l\u00e8ves Suzuki et nos coll\u00e8gues. Dans certains...<\/p>","protected":false},"author":3,"featured_media":323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"pmpro_default_level":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[66],"tags":[],"class_list":["post-696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada","pmpro-has-access"],"acf":[],"taxonomy_info":{"category":[{"value":66,"label":"Canada"}]},"featured_image_src_large":["https:\/\/suzukiassociation.org\/wp-content\/uploads\/2023\/01\/saa-logo.png",640,640,false],"author_info":{"display_name":"Moonlit Media","author_link":"https:\/\/suzukiassociation.org\/fr\/author\/moonlit\/"},"comment_info":6,"category_info":[{"term_id":66,"name":"Canada","slug":"canada","term_group":0,"term_taxonomy_id":66,"taxonomy":"category","description":"","parent":0,"count":10,"filter":"raw","cat_ID":66,"category_count":10,"category_description":"","cat_name":"Canada","category_nicename":"canada","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/posts\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":0,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/posts\/696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/media\/323"}],"wp:attachment":[{"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/media?parent=696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/categories?post=696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suzukiassociation.org\/fr\/wp-json\/wp\/v2\/tags?post=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}