{"id":95590,"date":"2026-07-10T19:18:29","date_gmt":"2026-07-11T01:18:29","guid":{"rendered":"https:\/\/suzukiassociation.org\/?post_type=tribe_events&#038;p=95590"},"modified":"2026-07-10T19:19:38","modified_gmt":"2026-07-11T01:19:38","slug":"violin-unit-1-66","status":"publish","type":"tribe_events","link":"https:\/\/suzukiassociation.org\/es\/event\/violin-unit-1-66\/","title":{"rendered":"Viol\u00edn Unidad 1"},"content":{"rendered":"<p style=\"font-weight: 400;\">Esta unidad uno de viol\u00edn con <em>Kirsten Marshall, instructora de la SAA<\/em> comienza el ciclo completo de la pedagog\u00eda del viol\u00edn Suzuki, con los libros del 1 al 10, a lo largo de un ciclo de dos a\u00f1os. Las clases seguir\u00e1n el calendario acad\u00e9mico de la Universidad de Louisville.<\/p>\n<p style=\"font-weight: 400;\">A lo largo del curso se har\u00e1 hincapi\u00e9 en una exploraci\u00f3n profunda de c\u00f3mo ense\u00f1ar a un ni\u00f1o a aprender de o\u00eddo, junto con el desarrollo de un manual que permita a un nuevo maestro Suzuki guiar con confianza a sus alumnos principiantes. \u00bfC\u00f3mo se lleva a cabo la pr\u00e1ctica diaria del entrenamiento auditivo en las clases y en casa? \u00bfC\u00f3mo podemos facilitar que nuestros alumnos y sus familias contin\u00faen practicando en casa? Basado en la filosof\u00eda del Dr. Suzuki sobre la educaci\u00f3n del talento, este curso presenta las habilidades fundamentales del m\u00e9todo Suzuki \u2014postura equilibrada, mano izquierda relajada y un bonito movimiento del arco\u2014 todo ello mientras se aprende con amor. Los participantes del taller tendr\u00e1n la oportunidad de hacer demostraciones en clase y se les recomienda que ya tengan memorizado el Libro 1. Las observaciones se realizar\u00e1n de manera asincr\u00f3nica y se discutir\u00e1n en cada clase.<\/p>\n<p><span style=\"font-weight: 400;\">La Universidad de Louisville con el formador SAA <em>Kirsten Marshall<\/em> ofrece la Unidad 1 en un formato ampliado que permitir\u00e1 un an\u00e1lisis en profundidad, un debate interactivo y la demostraci\u00f3n de los puntos clave de la ense\u00f1anza. Las clases se imparten en l\u00ednea los lunes de 9:00 a. m. a mediod\u00eda (hora del Este) durante diez sesiones. Las consultas individuales se programar\u00e1n los d\u00edas 2 y 3 de noviembre de 2026. <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><em>Todos los ni\u00f1os pueden<\/em> es un requisito previo para iniciar la pedagog\u00eda Suzuki y se impartir\u00e1 los d\u00edas 14 y 16 de agosto de 2026.<\/span><\/p>\n<h2><b><i>C\u00f3mo inscribirse<\/i><\/b><\/h2>\n<p><b><i>Debe estar conectado a su cuenta SAA y tener <\/i><\/b><a href=\"https:\/\/suzukiassociation.org\/es\/membership-account\/\" target=\"_blank\" rel=\"noopener\"><b><i>Afiliaci\u00f3n activa\/profesional<\/i><\/b><\/a> <i><span style=\"font-weight: 400;\">para inscribirte en el curso y pagar el dep\u00f3sito no reembolsable de $20, a continuaci\u00f3n.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Despl\u00e1cese hasta la parte inferior de esta p\u00e1gina hasta la casilla de inscripci\u00f3n, haga clic en \"+\" y, a continuaci\u00f3n, en \"conseguir entradas\". <\/span><\/i><b><i>Siga las instrucciones.<\/i><\/b><i><span style=\"font-weight: 400;\"> para ingresar su informaci\u00f3n de pago y responder estas preguntas antes de unirse a la lista:<\/span><\/i><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><i><span style=\"font-weight: 400;\">\u00bfEs licenciado en m\u00fasica?\u00a0<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><i><span style=\"font-weight: 400;\">En su mejor estimaci\u00f3n y<\/span><\/i><a href=\"https:\/\/suzukiassociation.org\/es\/teachers\/teacher-training\/audition-guidelines\/#audition-success\"> <i><span style=\"font-weight: 400;\">utilizando esta r\u00fabrica<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">, \u00bfpuedes realizar el <\/span><\/i><a href=\"https:\/\/suzukiassociation.org\/es\/teachers\/audition-repertoire\/\"><i><span style=\"font-weight: 400;\">Repertorio b\u00e1sico de audiciones<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">?<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><i><span style=\"font-weight: 400;\">Describa su experiencia docente e interpretativa con el instrumento.<\/span><\/i><\/li>\n<\/ul>\n<p><i><span style=\"font-weight: 400;\">Despu\u00e9s de comprar los boletos a continuaci\u00f3n, recibir\u00e1s un recibo y un correo electr\u00f3nico de confirmaci\u00f3n de la SAA con detalles sobre c\u00f3mo pagar el saldo de la matr\u00edcula del curso. Revisa tu carpeta de correo no deseado si no lo ves en tu bandeja de entrada.<\/span><\/i><\/p>\n<p><b><i>Si el cuadro de inscripci\u00f3n no est\u00e1 visible y solo ves la opci\u00f3n de lista de espera, significa que te falta el requisito previo del curso ECC en tu perfil de capacitaci\u00f3n.<\/i><\/b><i><span style=\"font-weight: 400;\"><strong> Por favor, inscr\u00edbase en la lista de espera<\/strong> mientras cumples con ese requisito. Puedes verificar tu estado en la lista de espera desde tu perfil:<\/span><\/i><a href=\"https:\/\/suzukiassociation.org\/es\/person-profile\/\"> <i><span style=\"font-weight: 400;\">https:\/\/suzukiassociation.org\/person-profile\/<\/span><\/i><\/a><\/p>\n<p><i><span style=\"font-weight: 400;\">Si tiene alg\u00fan problema para inscribirse o si es necesario actualizar su perfil, escriba a info@suzukiassociation.org con los detalles.\u00a0<\/span><\/i><\/p>\n<p><b><i>Todas las transacciones son definitivas y no reembolsables.<\/i><\/b><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>This Violin Unit One with SAA trainer Kirsten Marshall begins the complete cycle of Suzuki Violin pedagogy in books 1-10 over a two-year cycle. \u00a0The classes will follow the University&#8230;<\/p>","protected":false},"author":208053,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"pmpro_default_level":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[{\"id\":98266,\"type\":\"default\",\"title\":\"Enrollment\",\"description\":\"\",\"capacityType\":\"own\",\"price\":\"20.00\",\"capacity\":10,\"available\":10,\"sharedCapacity\":10,\"sold\":0,\"shareSold\":0,\"isShared\":false,\"currencyDecimalPoint\":\".\",\"currencyNumberOfDecimals\":2,\"currencyPosition\":\"prefix\",\"currencySymbol\":\"$\",\"currencyThousandsSep\":\",\"}]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[698],"class_list":["post-95590","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-unit-1","pmpro-has-access","cat_unit-1"],"acf":[],"taxonomy_info":{"tribe_events_cat":[{"value":698,"label":"Unit 1"}]},"featured_image_src_large":false,"author_info":{"display_name":"Kirsten Marshall","author_link":"https:\/\/suzukiassociation.org\/es\/author\/kirsten-marshall440gmail-com\/"},"comment_info":"","ticketed":["tc"],"_links":{"self":[{"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/tribe_events\/95590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/users\/208053"}],"version-history":[{"count":2,"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/tribe_events\/95590\/revisions"}],"predecessor-version":[{"id":98265,"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/tribe_events\/95590\/revisions\/98265"}],"wp:attachment":[{"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/media?parent=95590"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/tags?post=95590"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/suzukiassociation.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=95590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}